{"id":152846,"date":"2020-06-15T11:40:46","date_gmt":"2020-06-15T09:40:46","guid":{"rendered":"https:\/\/n.energylandia.pl\/noclegi\/apartamenty-pawelek\/"},"modified":"2025-07-28T12:11:54","modified_gmt":"2025-07-28T10:11:54","slug":"apartamenty-pawelek","status":"publish","type":"noclegi","link":"https:\/\/energylandia.pl\/sk\/ubytovanie\/apartamenty-pawelek\/","title":{"rendered":"Apartamenty Pawe\u0142ek"},"featured_media":0,"parent":0,"template":"","class_list":["post-152846","noclegi","type-noclegi","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Apartamenty Pawe\u0142ek - ubytovanie v bl\u00edzkosti z\u00e1bavn\u00e9ho parku | Energylandia<\/title>\n<meta name=\"description\" content=\"Apartamenty Pawe\u0142ek - komfortn\u00e9 ubytovanie v bl\u00edzkosti Energylandie. Ide\u00e1lne miesto na oddych po dni plnom z\u00e1\u017eitkov. Pozrite si ponuku a rezervujte si pobyt!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/energylandia.pl\/sk\/ubytovanie\/apartamenty-pawelek\/\" \/>\n<meta property=\"og:locale\" content=\"sk_SK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apartamenty Pawe\u0142ek - ubytovanie v bl\u00edzkosti z\u00e1bavn\u00e9ho parku | Energylandia\" \/>\n<meta property=\"og:description\" content=\"Apartamenty Pawe\u0142ek - komfortn\u00e9 ubytovanie v bl\u00edzkosti Energylandie. Ide\u00e1lne miesto na oddych po dni plnom z\u00e1\u017eitkov. Pozrite si ponuku a rezervujte si pobyt!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energylandia.pl\/sk\/ubytovanie\/apartamenty-pawelek\/\" \/>\n<meta property=\"og:site_name\" content=\"Energylandia - park \u010d. 1 na svete\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EnergyLandia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-28T10:11:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energylandia.pl\/sk\/ubytovanie\/apartamenty-pawelek\/\",\"url\":\"https:\/\/energylandia.pl\/sk\/ubytovanie\/apartamenty-pawelek\/\",\"name\":\"Apartamenty Pawe\u0142ek - ubytovanie v bl\u00edzkosti z\u00e1bavn\u00e9ho parku | Energylandia\",\"isPartOf\":{\"@id\":\"https:\/\/energylandia.pl\/#website\"},\"datePublished\":\"2020-06-15T09:40:46+00:00\",\"dateModified\":\"2025-07-28T10:11:54+00:00\",\"description\":\"Apartamenty Pawe\u0142ek - komfortn\u00e9 ubytovanie v bl\u00edzkosti Energylandie. Ide\u00e1lne miesto na oddych po dni plnom z\u00e1\u017eitkov. Pozrite si ponuku a rezervujte si pobyt!\",\"breadcrumb\":{\"@id\":\"https:\/\/energylandia.pl\/sk\/ubytovanie\/apartamenty-pawelek\/#breadcrumb\"},\"inLanguage\":\"sk-SK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energylandia.pl\/sk\/ubytovanie\/apartamenty-pawelek\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energylandia.pl\/sk\/ubytovanie\/apartamenty-pawelek\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/energylandia.pl\/sk\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noclegi\",\"item\":\"https:\/\/energylandia.pl\/uk\/noclegi\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Apartamenty Pawe\u0142ek\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energylandia.pl\/#website\",\"url\":\"https:\/\/energylandia.pl\/\",\"name\":\"Energylandia - park \u010d. 1 na svete\",\"description\":\"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!\",\"publisher\":{\"@id\":\"https:\/\/energylandia.pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energylandia.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sk-SK\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/energylandia.pl\/#organization\",\"name\":\"Energylandia\",\"url\":\"https:\/\/energylandia.pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sk-SK\",\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Energylandia\"},\"image\":{\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EnergyLandia\",\"https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA\",\"https:\/\/vm.tiktok.com\/Tw7YAK\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apartamenty Pawe\u0142ek - ubytovanie v bl\u00edzkosti z\u00e1bavn\u00e9ho parku | Energylandia","description":"Apartamenty Pawe\u0142ek - komfortn\u00e9 ubytovanie v bl\u00edzkosti Energylandie. Ide\u00e1lne miesto na oddych po dni plnom z\u00e1\u017eitkov. Pozrite si ponuku a rezervujte si pobyt!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energylandia.pl\/sk\/ubytovanie\/apartamenty-pawelek\/","og_locale":"sk_SK","og_type":"article","og_title":"Apartamenty Pawe\u0142ek - ubytovanie v bl\u00edzkosti z\u00e1bavn\u00e9ho parku | Energylandia","og_description":"Apartamenty Pawe\u0142ek - komfortn\u00e9 ubytovanie v bl\u00edzkosti Energylandie. Ide\u00e1lne miesto na oddych po dni plnom z\u00e1\u017eitkov. Pozrite si ponuku a rezervujte si pobyt!","og_url":"https:\/\/energylandia.pl\/sk\/ubytovanie\/apartamenty-pawelek\/","og_site_name":"Energylandia - park \u010d. 1 na svete","article_publisher":"https:\/\/www.facebook.com\/EnergyLandia","article_modified_time":"2025-07-28T10:11:54+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/energylandia.pl\/sk\/ubytovanie\/apartamenty-pawelek\/","url":"https:\/\/energylandia.pl\/sk\/ubytovanie\/apartamenty-pawelek\/","name":"Apartamenty Pawe\u0142ek - ubytovanie v bl\u00edzkosti z\u00e1bavn\u00e9ho parku | Energylandia","isPartOf":{"@id":"https:\/\/energylandia.pl\/#website"},"datePublished":"2020-06-15T09:40:46+00:00","dateModified":"2025-07-28T10:11:54+00:00","description":"Apartamenty Pawe\u0142ek - komfortn\u00e9 ubytovanie v bl\u00edzkosti Energylandie. Ide\u00e1lne miesto na oddych po dni plnom z\u00e1\u017eitkov. Pozrite si ponuku a rezervujte si pobyt!","breadcrumb":{"@id":"https:\/\/energylandia.pl\/sk\/ubytovanie\/apartamenty-pawelek\/#breadcrumb"},"inLanguage":"sk-SK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energylandia.pl\/sk\/ubytovanie\/apartamenty-pawelek\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/energylandia.pl\/sk\/ubytovanie\/apartamenty-pawelek\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/energylandia.pl\/sk\/"},{"@type":"ListItem","position":2,"name":"Noclegi","item":"https:\/\/energylandia.pl\/uk\/noclegi\/"},{"@type":"ListItem","position":3,"name":"Apartamenty Pawe\u0142ek"}]},{"@type":"WebSite","@id":"https:\/\/energylandia.pl\/#website","url":"https:\/\/energylandia.pl\/","name":"Energylandia - park \u010d. 1 na svete","description":"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!","publisher":{"@id":"https:\/\/energylandia.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energylandia.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sk-SK"},{"@type":"Organization","@id":"https:\/\/energylandia.pl\/#organization","name":"Energylandia","url":"https:\/\/energylandia.pl\/","logo":{"@type":"ImageObject","inLanguage":"sk-SK","@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Energylandia"},"image":{"@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EnergyLandia","https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA","https:\/\/vm.tiktok.com\/Tw7YAK\/"]}]}},"_links":{"self":[{"href":"https:\/\/energylandia.pl\/sk\/wp-json\/wp\/v2\/noclegi\/152846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energylandia.pl\/sk\/wp-json\/wp\/v2\/noclegi"}],"about":[{"href":"https:\/\/energylandia.pl\/sk\/wp-json\/wp\/v2\/types\/noclegi"}],"wp:attachment":[{"href":"https:\/\/energylandia.pl\/sk\/wp-json\/wp\/v2\/media?parent=152846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}