{"id":85026,"date":"2021-03-12T13:22:23","date_gmt":"2021-03-12T12:22:23","guid":{"rendered":"https:\/\/energylandia.pl\/?post_type=plm_atrakcje&#038;p=85026"},"modified":"2025-10-07T12:34:05","modified_gmt":"2025-10-07T10:34:05","slug":"deti-2-6-let","status":"publish","type":"atrakcje","link":"https:\/\/energylandia.pl\/sk\/atrakcie\/deti-2-6-let\/","title":{"rendered":"Deti 2-6 let"},"content":{"rendered":"","protected":false},"featured_media":85047,"parent":0,"menu_order":1329,"template":"","class_list":["post-85026","atrakcje","type-atrakcje","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Deti 2-6 let - Atrakcie pre deti | Energylandia<\/title>\n<meta name=\"description\" content=\"H\u013ead\u00e1te atrakcie pre najmen\u0161\u00edch? Pozrite si zoznam koloto\u010dov, horsk\u00fdch dr\u00e1h a ihr\u00edsk, ktor\u00e9 s\u00fa ide\u00e1lne pre deti vo veku 2-6 rokov v Energylandii. Napl\u00e1nujte si n\u00e1v\u0161tevu!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/energylandia.pl\/sk\/atrakcie\/deti-2-6-let\/\" \/>\n<meta property=\"og:locale\" content=\"sk_SK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deti 2-6 let - Atrakcie pre deti | Energylandia\" \/>\n<meta property=\"og:description\" content=\"H\u013ead\u00e1te atrakcie pre najmen\u0161\u00edch? Pozrite si zoznam koloto\u010dov, horsk\u00fdch dr\u00e1h a ihr\u00edsk, ktor\u00e9 s\u00fa ide\u00e1lne pre deti vo veku 2-6 rokov v Energylandii. Napl\u00e1nujte si n\u00e1v\u0161tevu!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energylandia.pl\/sk\/atrakcie\/deti-2-6-let\/\" \/>\n<meta property=\"og:site_name\" content=\"Energylandia - park \u010d. 1 na svete\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EnergyLandia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T10:34:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/energylandia.pl\/wp-content\/uploads\/2021\/03\/IMG_4154-900x600-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Predpokladan\u00fd \u010das \u010d\u00edtania\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 min\u00fata\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energylandia.pl\/sk\/atrakcie\/deti-2-6-let\/\",\"url\":\"https:\/\/energylandia.pl\/sk\/atrakcie\/deti-2-6-let\/\",\"name\":\"Deti 2-6 let - Atrakcie pre deti | Energylandia\",\"isPartOf\":{\"@id\":\"https:\/\/energylandia.pl\/#website\"},\"datePublished\":\"2021-03-12T12:22:23+00:00\",\"dateModified\":\"2025-10-07T10:34:05+00:00\",\"description\":\"H\u013ead\u00e1te atrakcie pre najmen\u0161\u00edch? Pozrite si zoznam koloto\u010dov, horsk\u00fdch dr\u00e1h a ihr\u00edsk, ktor\u00e9 s\u00fa ide\u00e1lne pre deti vo veku 2-6 rokov v Energylandii. Napl\u00e1nujte si n\u00e1v\u0161tevu!\",\"breadcrumb\":{\"@id\":\"https:\/\/energylandia.pl\/sk\/atrakcie\/deti-2-6-let\/#breadcrumb\"},\"inLanguage\":\"sk-SK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energylandia.pl\/sk\/atrakcie\/deti-2-6-let\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energylandia.pl\/sk\/atrakcie\/deti-2-6-let\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/energylandia.pl\/sk\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atrakcje\",\"item\":\"https:\/\/energylandia.pl\/uk\/\u0430\u0442\u0440\u0430\u043a\u0446\u0456\u0457\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Deti 2-6 let\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energylandia.pl\/#website\",\"url\":\"https:\/\/energylandia.pl\/\",\"name\":\"Energylandia - park \u010d. 1 na svete\",\"description\":\"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!\",\"publisher\":{\"@id\":\"https:\/\/energylandia.pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energylandia.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sk-SK\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/energylandia.pl\/#organization\",\"name\":\"Energylandia\",\"url\":\"https:\/\/energylandia.pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sk-SK\",\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Energylandia\"},\"image\":{\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EnergyLandia\",\"https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA\",\"https:\/\/vm.tiktok.com\/Tw7YAK\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deti 2-6 let - Atrakcie pre deti | Energylandia","description":"H\u013ead\u00e1te atrakcie pre najmen\u0161\u00edch? Pozrite si zoznam koloto\u010dov, horsk\u00fdch dr\u00e1h a ihr\u00edsk, ktor\u00e9 s\u00fa ide\u00e1lne pre deti vo veku 2-6 rokov v Energylandii. Napl\u00e1nujte si n\u00e1v\u0161tevu!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energylandia.pl\/sk\/atrakcie\/deti-2-6-let\/","og_locale":"sk_SK","og_type":"article","og_title":"Deti 2-6 let - Atrakcie pre deti | Energylandia","og_description":"H\u013ead\u00e1te atrakcie pre najmen\u0161\u00edch? Pozrite si zoznam koloto\u010dov, horsk\u00fdch dr\u00e1h a ihr\u00edsk, ktor\u00e9 s\u00fa ide\u00e1lne pre deti vo veku 2-6 rokov v Energylandii. Napl\u00e1nujte si n\u00e1v\u0161tevu!","og_url":"https:\/\/energylandia.pl\/sk\/atrakcie\/deti-2-6-let\/","og_site_name":"Energylandia - park \u010d. 1 na svete","article_publisher":"https:\/\/www.facebook.com\/EnergyLandia","article_modified_time":"2025-10-07T10:34:05+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/energylandia.pl\/wp-content\/uploads\/2021\/03\/IMG_4154-900x600-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Predpokladan\u00fd \u010das \u010d\u00edtania":"5 min\u00fata"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/energylandia.pl\/sk\/atrakcie\/deti-2-6-let\/","url":"https:\/\/energylandia.pl\/sk\/atrakcie\/deti-2-6-let\/","name":"Deti 2-6 let - Atrakcie pre deti | Energylandia","isPartOf":{"@id":"https:\/\/energylandia.pl\/#website"},"datePublished":"2021-03-12T12:22:23+00:00","dateModified":"2025-10-07T10:34:05+00:00","description":"H\u013ead\u00e1te atrakcie pre najmen\u0161\u00edch? Pozrite si zoznam koloto\u010dov, horsk\u00fdch dr\u00e1h a ihr\u00edsk, ktor\u00e9 s\u00fa ide\u00e1lne pre deti vo veku 2-6 rokov v Energylandii. Napl\u00e1nujte si n\u00e1v\u0161tevu!","breadcrumb":{"@id":"https:\/\/energylandia.pl\/sk\/atrakcie\/deti-2-6-let\/#breadcrumb"},"inLanguage":"sk-SK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energylandia.pl\/sk\/atrakcie\/deti-2-6-let\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/energylandia.pl\/sk\/atrakcie\/deti-2-6-let\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/energylandia.pl\/sk\/"},{"@type":"ListItem","position":2,"name":"Atrakcje","item":"https:\/\/energylandia.pl\/uk\/\u0430\u0442\u0440\u0430\u043a\u0446\u0456\u0457\/"},{"@type":"ListItem","position":3,"name":"Deti 2-6 let"}]},{"@type":"WebSite","@id":"https:\/\/energylandia.pl\/#website","url":"https:\/\/energylandia.pl\/","name":"Energylandia - park \u010d. 1 na svete","description":"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!","publisher":{"@id":"https:\/\/energylandia.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energylandia.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sk-SK"},{"@type":"Organization","@id":"https:\/\/energylandia.pl\/#organization","name":"Energylandia","url":"https:\/\/energylandia.pl\/","logo":{"@type":"ImageObject","inLanguage":"sk-SK","@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Energylandia"},"image":{"@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EnergyLandia","https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA","https:\/\/vm.tiktok.com\/Tw7YAK\/"]}]}},"_links":{"self":[{"href":"https:\/\/energylandia.pl\/sk\/wp-json\/wp\/v2\/atrakcje\/85026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energylandia.pl\/sk\/wp-json\/wp\/v2\/atrakcje"}],"about":[{"href":"https:\/\/energylandia.pl\/sk\/wp-json\/wp\/v2\/types\/atrakcje"}],"version-history":[{"count":1,"href":"https:\/\/energylandia.pl\/sk\/wp-json\/wp\/v2\/atrakcje\/85026\/revisions"}],"predecessor-version":[{"id":307040,"href":"https:\/\/energylandia.pl\/sk\/wp-json\/wp\/v2\/atrakcje\/85026\/revisions\/307040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energylandia.pl\/sk\/wp-json\/wp\/v2\/media\/85047"}],"wp:attachment":[{"href":"https:\/\/energylandia.pl\/sk\/wp-json\/wp\/v2\/media?parent=85026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}