{"id":155945,"date":"2016-03-25T14:57:54","date_gmt":"2016-03-25T13:57:54","guid":{"rendered":"https:\/\/n.energylandia.pl\/partnerzy\/"},"modified":"2025-04-09T12:07:21","modified_gmt":"2025-04-09T10:07:21","slug":"partneriai","status":"publish","type":"page","link":"https:\/\/energylandia.pl\/lt\/partneriai\/","title":{"rendered":"Partneriai"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":29,"featured_media":0,"parent":0,"menu_order":371,"comment_status":"closed","ping_status":"closed","template":"templates\/partnerzy.php","meta":{"footnotes":""},"class_list":["post-155945","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Partneriai - Energylandia - parkas Nr. 1 pasaulyje<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/energylandia.pl\/lt\/partneriai\/\" \/>\n<meta property=\"og:locale\" content=\"lt_LT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Partneriai - Energylandia - parkas Nr. 1 pasaulyje\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energylandia.pl\/lt\/partneriai\/\" \/>\n<meta property=\"og:site_name\" content=\"Energylandia - parkas Nr. 1 pasaulyje\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EnergyLandia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-09T10:07:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energylandia.pl\/lt\/partneriai\/\",\"url\":\"https:\/\/energylandia.pl\/lt\/partneriai\/\",\"name\":\"Partneriai - Energylandia - parkas Nr. 1 pasaulyje\",\"isPartOf\":{\"@id\":\"https:\/\/energylandia.pl\/#website\"},\"datePublished\":\"2016-03-25T13:57:54+00:00\",\"dateModified\":\"2025-04-09T10:07:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/energylandia.pl\/lt\/partneriai\/#breadcrumb\"},\"inLanguage\":\"lt-LT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energylandia.pl\/lt\/partneriai\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energylandia.pl\/lt\/partneriai\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/energylandia.pl\/lt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Partneriai\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energylandia.pl\/#website\",\"url\":\"https:\/\/energylandia.pl\/\",\"name\":\"Energylandia - parkas Nr. 1 pasaulyje\",\"description\":\"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!\",\"publisher\":{\"@id\":\"https:\/\/energylandia.pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energylandia.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"lt-LT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/energylandia.pl\/#organization\",\"name\":\"Energylandia\",\"url\":\"https:\/\/energylandia.pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"lt-LT\",\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Energylandia\"},\"image\":{\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EnergyLandia\",\"https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA\",\"https:\/\/vm.tiktok.com\/Tw7YAK\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Partneriai - Energylandia - parkas Nr. 1 pasaulyje","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energylandia.pl\/lt\/partneriai\/","og_locale":"lt_LT","og_type":"article","og_title":"Partneriai - Energylandia - parkas Nr. 1 pasaulyje","og_url":"https:\/\/energylandia.pl\/lt\/partneriai\/","og_site_name":"Energylandia - parkas Nr. 1 pasaulyje","article_publisher":"https:\/\/www.facebook.com\/EnergyLandia","article_modified_time":"2025-04-09T10:07:21+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/energylandia.pl\/lt\/partneriai\/","url":"https:\/\/energylandia.pl\/lt\/partneriai\/","name":"Partneriai - Energylandia - parkas Nr. 1 pasaulyje","isPartOf":{"@id":"https:\/\/energylandia.pl\/#website"},"datePublished":"2016-03-25T13:57:54+00:00","dateModified":"2025-04-09T10:07:21+00:00","breadcrumb":{"@id":"https:\/\/energylandia.pl\/lt\/partneriai\/#breadcrumb"},"inLanguage":"lt-LT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energylandia.pl\/lt\/partneriai\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/energylandia.pl\/lt\/partneriai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/energylandia.pl\/lt\/"},{"@type":"ListItem","position":2,"name":"Partneriai"}]},{"@type":"WebSite","@id":"https:\/\/energylandia.pl\/#website","url":"https:\/\/energylandia.pl\/","name":"Energylandia - parkas Nr. 1 pasaulyje","description":"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!","publisher":{"@id":"https:\/\/energylandia.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energylandia.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"lt-LT"},{"@type":"Organization","@id":"https:\/\/energylandia.pl\/#organization","name":"Energylandia","url":"https:\/\/energylandia.pl\/","logo":{"@type":"ImageObject","inLanguage":"lt-LT","@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Energylandia"},"image":{"@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EnergyLandia","https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA","https:\/\/vm.tiktok.com\/Tw7YAK\/"]}]}},"_links":{"self":[{"href":"https:\/\/energylandia.pl\/lt\/wp-json\/wp\/v2\/pages\/155945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energylandia.pl\/lt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/energylandia.pl\/lt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/energylandia.pl\/lt\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/energylandia.pl\/lt\/wp-json\/wp\/v2\/comments?post=155945"}],"version-history":[{"count":1,"href":"https:\/\/energylandia.pl\/lt\/wp-json\/wp\/v2\/pages\/155945\/revisions"}],"predecessor-version":[{"id":155946,"href":"https:\/\/energylandia.pl\/lt\/wp-json\/wp\/v2\/pages\/155945\/revisions\/155946"}],"wp:attachment":[{"href":"https:\/\/energylandia.pl\/lt\/wp-json\/wp\/v2\/media?parent=155945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}