{"id":296026,"date":"2017-02-14T21:25:23","date_gmt":"2017-02-14T20:25:23","guid":{"rendered":"https:\/\/energylandia.pl\/atrakcje\/apocalipto\/"},"modified":"2026-02-20T08:28:58","modified_gmt":"2026-02-20T07:28:58","slug":"apocalipto","status":"publish","type":"atrakcje","link":"https:\/\/energylandia.pl\/it\/attrazioni\/zona-estrema\/apocalipto\/","title":{"rendered":"Apocalypto"},"content":{"rendered":"<p>Apocalypto \u00e8 una delle attrazioni pi\u00f9 estreme del pi\u00f9 grande parco divertimenti della Polonia. La panca \u00e8 montata su un\u2019imponente struttura a doppio braccio con un diametro di 8 metri, che mette l\u2019intero impianto in un movimento rotatorio dinamico. \ud83d\udd04<\/p>\n<p>Durante il giro, la panca si muove lungo una traiettoria circolare e le forze d\u2019inerzia provocano ulteriori rotazioni incontrollate attorno al proprio asse. Il risultato? Forti sollecitazioni multidirezionali e una scarica di adrenalina garantita! \u26a1<\/p>\n<p>L\u2019attrazione pu\u00f2 ospitare fino a 18 persone contemporaneamente. \ud83d\udc65<\/p>\n<p>\u2139\ufe0f Informazioni tecniche:<\/p>\n<p>Diametro della struttura: 8 metri<\/p>\n<p>Capacit\u00e0 massima: 18 persone<\/p>\n<p>Altezza minima: 140 cm \ud83d\udccf<\/p>\n<p>Sei pronto alla sfida? \ud83d\ude80<\/p>\n","protected":false},"featured_media":0,"parent":297748,"menu_order":681,"template":"","class_list":["post-296026","atrakcje","type-atrakcje","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Apocalypto - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apocalypto - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\" \/>\n<meta property=\"og:description\" content=\"Apocalypto \u00e8 una delle attrazioni pi\u00f9 estreme del pi\u00f9 grande parco divertimenti della Polonia. La panca \u00e8 montata su un\u2019imponente struttura a doppio braccio con un diametro di 8 metri, che mette l\u2019intero impianto in un movimento rotatorio dinamico. \ud83d\udd04 Durante il giro, la panca si muove lungo una traiettoria circolare e le forze d\u2019inerzia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-estrema\/apocalipto\/\" \/>\n<meta property=\"og:site_name\" content=\"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EnergyLandia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-20T07:28:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-estrema\/apocalipto\/\",\"url\":\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-estrema\/apocalipto\/\",\"name\":\"Apocalypto - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\",\"isPartOf\":{\"@id\":\"https:\/\/energylandia.pl\/#website\"},\"datePublished\":\"2017-02-14T20:25:23+00:00\",\"dateModified\":\"2026-02-20T07:28:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-estrema\/apocalipto\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-estrema\/apocalipto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-estrema\/apocalipto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/energylandia.pl\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atrakcje\",\"item\":\"https:\/\/energylandia.pl\/atrakcje\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zona Estrema\",\"item\":\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-estrema\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Apocalypto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energylandia.pl\/#website\",\"url\":\"https:\/\/energylandia.pl\/\",\"name\":\"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\",\"description\":\"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!\",\"publisher\":{\"@id\":\"https:\/\/energylandia.pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energylandia.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/energylandia.pl\/#organization\",\"name\":\"Energylandia\",\"url\":\"https:\/\/energylandia.pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Energylandia\"},\"image\":{\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EnergyLandia\",\"https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA\",\"https:\/\/vm.tiktok.com\/Tw7YAK\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apocalypto - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Apocalypto - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","og_description":"Apocalypto \u00e8 una delle attrazioni pi\u00f9 estreme del pi\u00f9 grande parco divertimenti della Polonia. La panca \u00e8 montata su un\u2019imponente struttura a doppio braccio con un diametro di 8 metri, che mette l\u2019intero impianto in un movimento rotatorio dinamico. \ud83d\udd04 Durante il giro, la panca si muove lungo una traiettoria circolare e le forze d\u2019inerzia [&hellip;]","og_url":"https:\/\/energylandia.pl\/it\/atrakcje\/zona-estrema\/apocalipto\/","og_site_name":"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","article_publisher":"https:\/\/www.facebook.com\/EnergyLandia","article_modified_time":"2026-02-20T07:28:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/energylandia.pl\/it\/atrakcje\/zona-estrema\/apocalipto\/","url":"https:\/\/energylandia.pl\/it\/atrakcje\/zona-estrema\/apocalipto\/","name":"Apocalypto - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","isPartOf":{"@id":"https:\/\/energylandia.pl\/#website"},"datePublished":"2017-02-14T20:25:23+00:00","dateModified":"2026-02-20T07:28:58+00:00","breadcrumb":{"@id":"https:\/\/energylandia.pl\/it\/atrakcje\/zona-estrema\/apocalipto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energylandia.pl\/it\/atrakcje\/zona-estrema\/apocalipto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/energylandia.pl\/it\/atrakcje\/zona-estrema\/apocalipto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/energylandia.pl\/it\/"},{"@type":"ListItem","position":2,"name":"Atrakcje","item":"https:\/\/energylandia.pl\/atrakcje\/"},{"@type":"ListItem","position":3,"name":"Zona Estrema","item":"https:\/\/energylandia.pl\/it\/atrakcje\/zona-estrema\/"},{"@type":"ListItem","position":4,"name":"Apocalypto"}]},{"@type":"WebSite","@id":"https:\/\/energylandia.pl\/#website","url":"https:\/\/energylandia.pl\/","name":"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","description":"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!","publisher":{"@id":"https:\/\/energylandia.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energylandia.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/energylandia.pl\/#organization","name":"Energylandia","url":"https:\/\/energylandia.pl\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Energylandia"},"image":{"@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EnergyLandia","https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA","https:\/\/vm.tiktok.com\/Tw7YAK\/"]}]}},"_links":{"self":[{"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/atrakcje\/296026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/atrakcje"}],"about":[{"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/types\/atrakcje"}],"version-history":[{"count":2,"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/atrakcje\/296026\/revisions"}],"predecessor-version":[{"id":311890,"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/atrakcje\/296026\/revisions\/311890"}],"up":[{"embeddable":true,"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/atrakcje\/297748"}],"wp:attachment":[{"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/media?parent=296026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}