{"id":295986,"date":"2017-03-23T13:51:26","date_gmt":"2017-03-23T12:51:26","guid":{"rendered":"https:\/\/energylandia.pl\/atrakcje\/anaconda\/"},"modified":"2026-02-19T14:13:38","modified_gmt":"2026-02-19T13:13:38","slug":"anaconda","status":"publish","type":"atrakcje","link":"https:\/\/energylandia.pl\/it\/attrazioni\/zona-famiglia\/anaconda\/","title":{"rendered":"Anaconda"},"content":{"rendered":"<p><span data-sheets-root=\"1\">Spill Water Anaconda \u00e8 un&#8217;emozionante corsa in enormi imbarcazioni da 20 persone lungo un percorso pieno di sorprese bagnate. Le ripide cascate fanno accelerare i carri fino a 55 km\/h per colpire la superficie dell&#8217;acqua con grande slancio e creare un&#8217;onda spettacolare. Vi garantiamo che nessuno uscir\u00e0 asciutto da questa corsa!<br \/>\nGli effetti speciali perfettamente integrati, l&#8217;attrazione della corsa e l&#8217;esplosione di gioia fanno s\u00ec che questo tipo di attrazioni siano amate da intere famiglie. Anaconda \u00e8 dotata di ben 8 barche! Il produttore di questa attrazione \u00e8 INTAMIN, un&#8217;azienda svizzera specializzata nella produzione delle pi\u00f9 grandi attrezzature al mondo per parchi di divertimento.<\/span><\/p>\n<p>I bambini di altezza compresa tra 120 e 140 cm possono accedere all&#8217;attrazione se accompagnati.\ud83d\udca6\ud83d\udc0d<\/p>\n","protected":false},"featured_media":0,"parent":297738,"menu_order":644,"template":"","class_list":["post-295986","atrakcje","type-atrakcje","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Anaconda - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anaconda - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\" \/>\n<meta property=\"og:description\" content=\"Spill Water Anaconda \u00e8 un&#8217;emozionante corsa in enormi imbarcazioni da 20 persone lungo un percorso pieno di sorprese bagnate. Le ripide cascate fanno accelerare i carri fino a 55 km\/h per colpire la superficie dell&#8217;acqua con grande slancio e creare un&#8217;onda spettacolare. Vi garantiamo che nessuno uscir\u00e0 asciutto da questa corsa! Gli effetti speciali perfettamente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/anaconda\/\" \/>\n<meta property=\"og:site_name\" content=\"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EnergyLandia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-19T13:13:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/anaconda\/\",\"url\":\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/anaconda\/\",\"name\":\"Anaconda - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\",\"isPartOf\":{\"@id\":\"https:\/\/energylandia.pl\/#website\"},\"datePublished\":\"2017-03-23T12:51:26+00:00\",\"dateModified\":\"2026-02-19T13:13:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/anaconda\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/anaconda\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/anaconda\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/energylandia.pl\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atrakcje\",\"item\":\"https:\/\/energylandia.pl\/atrakcje\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zona Famiglia\",\"item\":\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Anaconda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energylandia.pl\/#website\",\"url\":\"https:\/\/energylandia.pl\/\",\"name\":\"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\",\"description\":\"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!\",\"publisher\":{\"@id\":\"https:\/\/energylandia.pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energylandia.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/energylandia.pl\/#organization\",\"name\":\"Energylandia\",\"url\":\"https:\/\/energylandia.pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Energylandia\"},\"image\":{\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EnergyLandia\",\"https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA\",\"https:\/\/vm.tiktok.com\/Tw7YAK\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anaconda - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Anaconda - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","og_description":"Spill Water Anaconda \u00e8 un&#8217;emozionante corsa in enormi imbarcazioni da 20 persone lungo un percorso pieno di sorprese bagnate. Le ripide cascate fanno accelerare i carri fino a 55 km\/h per colpire la superficie dell&#8217;acqua con grande slancio e creare un&#8217;onda spettacolare. Vi garantiamo che nessuno uscir\u00e0 asciutto da questa corsa! Gli effetti speciali perfettamente [&hellip;]","og_url":"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/anaconda\/","og_site_name":"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","article_publisher":"https:\/\/www.facebook.com\/EnergyLandia","article_modified_time":"2026-02-19T13:13:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/anaconda\/","url":"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/anaconda\/","name":"Anaconda - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","isPartOf":{"@id":"https:\/\/energylandia.pl\/#website"},"datePublished":"2017-03-23T12:51:26+00:00","dateModified":"2026-02-19T13:13:38+00:00","breadcrumb":{"@id":"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/anaconda\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/anaconda\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/anaconda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/energylandia.pl\/it\/"},{"@type":"ListItem","position":2,"name":"Atrakcje","item":"https:\/\/energylandia.pl\/atrakcje\/"},{"@type":"ListItem","position":3,"name":"Zona Famiglia","item":"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/"},{"@type":"ListItem","position":4,"name":"Anaconda"}]},{"@type":"WebSite","@id":"https:\/\/energylandia.pl\/#website","url":"https:\/\/energylandia.pl\/","name":"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","description":"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!","publisher":{"@id":"https:\/\/energylandia.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energylandia.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/energylandia.pl\/#organization","name":"Energylandia","url":"https:\/\/energylandia.pl\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Energylandia"},"image":{"@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EnergyLandia","https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA","https:\/\/vm.tiktok.com\/Tw7YAK\/"]}]}},"_links":{"self":[{"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/atrakcje\/295986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/atrakcje"}],"about":[{"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/types\/atrakcje"}],"version-history":[{"count":3,"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/atrakcje\/295986\/revisions"}],"predecessor-version":[{"id":311816,"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/atrakcje\/295986\/revisions\/311816"}],"up":[{"embeddable":true,"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/atrakcje\/297738"}],"wp:attachment":[{"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/media?parent=295986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}