{"id":295900,"date":"2017-02-15T13:59:04","date_gmt":"2017-02-15T12:59:04","guid":{"rendered":"https:\/\/energylandia.pl\/atrakcje\/formula-autodrom\/"},"modified":"2026-02-18T16:02:17","modified_gmt":"2026-02-18T15:02:17","slug":"formula-autodrom","status":"publish","type":"atrakcje","link":"https:\/\/energylandia.pl\/it\/attrazioni\/zona-famiglia\/formula-autodrom\/","title":{"rendered":"Formu\u0142a Autodrom"},"content":{"rendered":"<p>\ud83d\ude97 Formu\u0142a Autodrom \u00e8 un\u2019attrazione classica che regala tantissimo divertimento agli ospiti di tutte le et\u00e0 \u2013 adulti e bambini pi\u00f9 piccoli. Gli entusiasmanti scontri con altri veicoli e le gare amichevoli sul percorso garantiscono sorrisi a tutti.<\/p>\n<p>Grazie alle cinture di sicurezza speciali, il giro \u00e8 completamente confortevole e sicuro. I bambini dall\u2019altezza di 120 cm possono godersi l\u2019attrazione, rendendo Formu\u0142a Autodrom la scelta perfetta per il divertimento in famiglia. \ud83c\udf89\ud83c\udfce\ufe0f<\/p>\n","protected":false},"featured_media":0,"parent":297738,"menu_order":350,"template":"","class_list":["post-295900","atrakcje","type-atrakcje","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Formu\u0142a Autodrom - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formu\u0142a Autodrom - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\" \/>\n<meta property=\"og:description\" content=\"\ud83d\ude97 Formu\u0142a Autodrom \u00e8 un\u2019attrazione classica che regala tantissimo divertimento agli ospiti di tutte le et\u00e0 \u2013 adulti e bambini pi\u00f9 piccoli. Gli entusiasmanti scontri con altri veicoli e le gare amichevoli sul percorso garantiscono sorrisi a tutti. Grazie alle cinture di sicurezza speciali, il giro \u00e8 completamente confortevole e sicuro. I bambini dall\u2019altezza di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/formula-autodrom\/\" \/>\n<meta property=\"og:site_name\" content=\"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EnergyLandia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-18T15:02:17+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/formula-autodrom\/\",\"url\":\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/formula-autodrom\/\",\"name\":\"Formu\u0142a Autodrom - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\",\"isPartOf\":{\"@id\":\"https:\/\/energylandia.pl\/#website\"},\"datePublished\":\"2017-02-15T12:59:04+00:00\",\"dateModified\":\"2026-02-18T15:02:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/formula-autodrom\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/formula-autodrom\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/formula-autodrom\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/energylandia.pl\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atrakcje\",\"item\":\"https:\/\/energylandia.pl\/atrakcje\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zona Famiglia\",\"item\":\"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Formu\u0142a Autodrom\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energylandia.pl\/#website\",\"url\":\"https:\/\/energylandia.pl\/\",\"name\":\"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\",\"description\":\"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!\",\"publisher\":{\"@id\":\"https:\/\/energylandia.pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energylandia.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/energylandia.pl\/#organization\",\"name\":\"Energylandia\",\"url\":\"https:\/\/energylandia.pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Energylandia\"},\"image\":{\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EnergyLandia\",\"https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA\",\"https:\/\/vm.tiktok.com\/Tw7YAK\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Formu\u0142a Autodrom - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Formu\u0142a Autodrom - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","og_description":"\ud83d\ude97 Formu\u0142a Autodrom \u00e8 un\u2019attrazione classica che regala tantissimo divertimento agli ospiti di tutte le et\u00e0 \u2013 adulti e bambini pi\u00f9 piccoli. Gli entusiasmanti scontri con altri veicoli e le gare amichevoli sul percorso garantiscono sorrisi a tutti. Grazie alle cinture di sicurezza speciali, il giro \u00e8 completamente confortevole e sicuro. I bambini dall\u2019altezza di [&hellip;]","og_url":"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/formula-autodrom\/","og_site_name":"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","article_publisher":"https:\/\/www.facebook.com\/EnergyLandia","article_modified_time":"2026-02-18T15:02:17+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/formula-autodrom\/","url":"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/formula-autodrom\/","name":"Formu\u0142a Autodrom - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","isPartOf":{"@id":"https:\/\/energylandia.pl\/#website"},"datePublished":"2017-02-15T12:59:04+00:00","dateModified":"2026-02-18T15:02:17+00:00","breadcrumb":{"@id":"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/formula-autodrom\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/formula-autodrom\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/formula-autodrom\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/energylandia.pl\/it\/"},{"@type":"ListItem","position":2,"name":"Atrakcje","item":"https:\/\/energylandia.pl\/atrakcje\/"},{"@type":"ListItem","position":3,"name":"Zona Famiglia","item":"https:\/\/energylandia.pl\/it\/atrakcje\/zona-famiglia\/"},{"@type":"ListItem","position":4,"name":"Formu\u0142a Autodrom"}]},{"@type":"WebSite","@id":"https:\/\/energylandia.pl\/#website","url":"https:\/\/energylandia.pl\/","name":"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","description":"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!","publisher":{"@id":"https:\/\/energylandia.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energylandia.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/energylandia.pl\/#organization","name":"Energylandia","url":"https:\/\/energylandia.pl\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Energylandia"},"image":{"@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EnergyLandia","https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA","https:\/\/vm.tiktok.com\/Tw7YAK\/"]}]}},"_links":{"self":[{"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/atrakcje\/295900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/atrakcje"}],"about":[{"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/types\/atrakcje"}],"version-history":[{"count":3,"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/atrakcje\/295900\/revisions"}],"predecessor-version":[{"id":311559,"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/atrakcje\/295900\/revisions\/311559"}],"up":[{"embeddable":true,"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/atrakcje\/297738"}],"wp:attachment":[{"href":"https:\/\/energylandia.pl\/it\/wp-json\/wp\/v2\/media?parent=295900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}