{"id":297772,"date":"2014-07-01T23:08:40","date_gmt":"2014-07-01T21:08:40","guid":{"rendered":"https:\/\/energylandia.pl\/cennik\/"},"modified":"2026-06-29T13:08:52","modified_gmt":"2026-06-29T11:08:52","slug":"cennik","status":"publish","type":"page","link":"https:\/\/energylandia.pl\/fr\/cennik\/","title":{"rendered":"Cennik"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":29,"featured_media":0,"parent":0,"menu_order":373,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-297772","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cennik - Energylandia - montagnes russes n\u00b01<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/energylandia.pl\/fr\/cennik\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cennik - Energylandia - montagnes russes n\u00b01\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energylandia.pl\/fr\/cennik\/\" \/>\n<meta property=\"og:site_name\" content=\"Energylandia - montagnes russes n\u00b01\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EnergyLandia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-29T11:08:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energylandia.pl\/fr\/cennik\/\",\"url\":\"https:\/\/energylandia.pl\/fr\/cennik\/\",\"name\":\"Cennik - Energylandia - montagnes russes n\u00b01\",\"isPartOf\":{\"@id\":\"https:\/\/energylandia.pl\/#website\"},\"datePublished\":\"2014-07-01T21:08:40+00:00\",\"dateModified\":\"2026-06-29T11:08:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/energylandia.pl\/fr\/cennik\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energylandia.pl\/fr\/cennik\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energylandia.pl\/fr\/cennik\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/energylandia.pl\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cennik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energylandia.pl\/#website\",\"url\":\"https:\/\/energylandia.pl\/\",\"name\":\"Energylandia - montagnes russes n\u00b01\",\"description\":\"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!\",\"publisher\":{\"@id\":\"https:\/\/energylandia.pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energylandia.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/energylandia.pl\/#organization\",\"name\":\"Energylandia\",\"url\":\"https:\/\/energylandia.pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Energylandia\"},\"image\":{\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EnergyLandia\",\"https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA\",\"https:\/\/vm.tiktok.com\/Tw7YAK\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cennik - Energylandia - montagnes russes n\u00b01","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energylandia.pl\/fr\/cennik\/","og_locale":"fr_FR","og_type":"article","og_title":"Cennik - Energylandia - montagnes russes n\u00b01","og_url":"https:\/\/energylandia.pl\/fr\/cennik\/","og_site_name":"Energylandia - montagnes russes n\u00b01","article_publisher":"https:\/\/www.facebook.com\/EnergyLandia","article_modified_time":"2026-06-29T11:08:52+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/energylandia.pl\/fr\/cennik\/","url":"https:\/\/energylandia.pl\/fr\/cennik\/","name":"Cennik - Energylandia - montagnes russes n\u00b01","isPartOf":{"@id":"https:\/\/energylandia.pl\/#website"},"datePublished":"2014-07-01T21:08:40+00:00","dateModified":"2026-06-29T11:08:52+00:00","breadcrumb":{"@id":"https:\/\/energylandia.pl\/fr\/cennik\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energylandia.pl\/fr\/cennik\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/energylandia.pl\/fr\/cennik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/energylandia.pl\/fr\/"},{"@type":"ListItem","position":2,"name":"Cennik"}]},{"@type":"WebSite","@id":"https:\/\/energylandia.pl\/#website","url":"https:\/\/energylandia.pl\/","name":"Energylandia - montagnes russes n\u00b01","description":"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!","publisher":{"@id":"https:\/\/energylandia.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energylandia.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/energylandia.pl\/#organization","name":"Energylandia","url":"https:\/\/energylandia.pl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Energylandia"},"image":{"@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EnergyLandia","https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA","https:\/\/vm.tiktok.com\/Tw7YAK\/"]}]}},"_links":{"self":[{"href":"https:\/\/energylandia.pl\/fr\/wp-json\/wp\/v2\/pages\/297772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energylandia.pl\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/energylandia.pl\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/energylandia.pl\/fr\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/energylandia.pl\/fr\/wp-json\/wp\/v2\/comments?post=297772"}],"version-history":[{"count":2,"href":"https:\/\/energylandia.pl\/fr\/wp-json\/wp\/v2\/pages\/297772\/revisions"}],"predecessor-version":[{"id":325036,"href":"https:\/\/energylandia.pl\/fr\/wp-json\/wp\/v2\/pages\/297772\/revisions\/325036"}],"wp:attachment":[{"href":"https:\/\/energylandia.pl\/fr\/wp-json\/wp\/v2\/media?parent=297772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}