{"id":22750,"date":"2017-04-01T16:11:42","date_gmt":"2017-04-01T14:11:42","guid":{"rendered":"https:\/\/energylandia.pl\/de\/?post_type=plm_atrakcje&#038;p=22750"},"modified":"2026-02-20T08:28:38","modified_gmt":"2026-02-20T07:28:38","slug":"apocalipto","status":"publish","type":"atrakcje","link":"https:\/\/energylandia.pl\/de\/attraktionen\/adrenalin-zone\/apocalipto\/","title":{"rendered":"Apocalypto"},"content":{"rendered":"<p>Apocalypto ist eine der extremsten Attraktionen im gr\u00f6\u00dften Freizeitpark Polens. Die bankf\u00f6rmige Anlage ist auf einer beeindruckenden, doppelarmigen Konstruktion mit einem Durchmesser von 8 Metern montiert, die das gesamte Ger\u00e4t in eine dynamische Drehbewegung versetzt. \ud83d\udd04<\/p>\n<p>W\u00e4hrend der Fahrt bewegt sich die Bank auf einer Kreisbahn, und die wirkenden Fliehkr\u00e4fte verursachen zus\u00e4tzliche, unkontrollierte Drehungen um die eigene Achse. Das Ergebnis? Starke, wechselnde Belastungen und maximale Adrenalinaussch\u00fcttung! \u26a1<\/p>\n<p>Die Attraktion bietet Platz f\u00fcr bis zu 18 Personen gleichzeitig. \ud83d\udc65<\/p>\n<p>\u2139\ufe0f Technische Daten:<\/p>\n<p>Durchmesser der Konstruktion: 8 Meter<\/p>\n<p>Maximale Kapazit\u00e4t: 18 Personen<\/p>\n<p>Mindestgr\u00f6\u00dfe: 140 cm \ud83d\udccf<\/p>\n<p>Bereit f\u00fcr das Abenteuer? \ud83d\ude80<\/p>\n","protected":false},"featured_media":0,"parent":22719,"menu_order":684,"template":"","class_list":["post-22750","atrakcje","type-atrakcje","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Apocalypto - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apocalypto - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\" \/>\n<meta property=\"og:description\" content=\"Apocalypto ist eine der extremsten Attraktionen im gr\u00f6\u00dften Freizeitpark Polens. Die bankf\u00f6rmige Anlage ist auf einer beeindruckenden, doppelarmigen Konstruktion mit einem Durchmesser von 8 Metern montiert, die das gesamte Ger\u00e4t in eine dynamische Drehbewegung versetzt. \ud83d\udd04 W\u00e4hrend der Fahrt bewegt sich die Bank auf einer Kreisbahn, und die wirkenden Fliehkr\u00e4fte verursachen zus\u00e4tzliche, unkontrollierte Drehungen um [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energylandia.pl\/de\/atrakcje\/adrenalin-zone\/apocalipto\/\" \/>\n<meta property=\"og:site_name\" content=\"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EnergyLandia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-20T07:28:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energylandia.pl\/de\/atrakcje\/adrenalin-zone\/apocalipto\/\",\"url\":\"https:\/\/energylandia.pl\/de\/atrakcje\/adrenalin-zone\/apocalipto\/\",\"name\":\"Apocalypto - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\",\"isPartOf\":{\"@id\":\"https:\/\/energylandia.pl\/#website\"},\"datePublished\":\"2017-04-01T14:11:42+00:00\",\"dateModified\":\"2026-02-20T07:28:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/energylandia.pl\/de\/atrakcje\/adrenalin-zone\/apocalipto\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energylandia.pl\/de\/atrakcje\/adrenalin-zone\/apocalipto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energylandia.pl\/de\/atrakcje\/adrenalin-zone\/apocalipto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/energylandia.pl\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atrakcje\",\"item\":\"https:\/\/energylandia.pl\/atrakcje\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adrenalin Zone\",\"item\":\"https:\/\/energylandia.pl\/de\/atrakcje\/adrenalin-zone\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Apocalypto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energylandia.pl\/#website\",\"url\":\"https:\/\/energylandia.pl\/\",\"name\":\"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\",\"description\":\"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!\",\"publisher\":{\"@id\":\"https:\/\/energylandia.pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energylandia.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/energylandia.pl\/#organization\",\"name\":\"Energylandia\",\"url\":\"https:\/\/energylandia.pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Energylandia\"},\"image\":{\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EnergyLandia\",\"https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA\",\"https:\/\/vm.tiktok.com\/Tw7YAK\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apocalypto - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Apocalypto - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","og_description":"Apocalypto ist eine der extremsten Attraktionen im gr\u00f6\u00dften Freizeitpark Polens. Die bankf\u00f6rmige Anlage ist auf einer beeindruckenden, doppelarmigen Konstruktion mit einem Durchmesser von 8 Metern montiert, die das gesamte Ger\u00e4t in eine dynamische Drehbewegung versetzt. \ud83d\udd04 W\u00e4hrend der Fahrt bewegt sich die Bank auf einer Kreisbahn, und die wirkenden Fliehkr\u00e4fte verursachen zus\u00e4tzliche, unkontrollierte Drehungen um [&hellip;]","og_url":"https:\/\/energylandia.pl\/de\/atrakcje\/adrenalin-zone\/apocalipto\/","og_site_name":"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","article_publisher":"https:\/\/www.facebook.com\/EnergyLandia","article_modified_time":"2026-02-20T07:28:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/energylandia.pl\/de\/atrakcje\/adrenalin-zone\/apocalipto\/","url":"https:\/\/energylandia.pl\/de\/atrakcje\/adrenalin-zone\/apocalipto\/","name":"Apocalypto - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","isPartOf":{"@id":"https:\/\/energylandia.pl\/#website"},"datePublished":"2017-04-01T14:11:42+00:00","dateModified":"2026-02-20T07:28:38+00:00","breadcrumb":{"@id":"https:\/\/energylandia.pl\/de\/atrakcje\/adrenalin-zone\/apocalipto\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energylandia.pl\/de\/atrakcje\/adrenalin-zone\/apocalipto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/energylandia.pl\/de\/atrakcje\/adrenalin-zone\/apocalipto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/energylandia.pl\/de\/"},{"@type":"ListItem","position":2,"name":"Atrakcje","item":"https:\/\/energylandia.pl\/atrakcje\/"},{"@type":"ListItem","position":3,"name":"Adrenalin Zone","item":"https:\/\/energylandia.pl\/de\/atrakcje\/adrenalin-zone\/"},{"@type":"ListItem","position":4,"name":"Apocalypto"}]},{"@type":"WebSite","@id":"https:\/\/energylandia.pl\/#website","url":"https:\/\/energylandia.pl\/","name":"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","description":"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!","publisher":{"@id":"https:\/\/energylandia.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energylandia.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/energylandia.pl\/#organization","name":"Energylandia","url":"https:\/\/energylandia.pl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Energylandia"},"image":{"@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EnergyLandia","https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA","https:\/\/vm.tiktok.com\/Tw7YAK\/"]}]}},"_links":{"self":[{"href":"https:\/\/energylandia.pl\/de\/wp-json\/wp\/v2\/atrakcje\/22750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energylandia.pl\/de\/wp-json\/wp\/v2\/atrakcje"}],"about":[{"href":"https:\/\/energylandia.pl\/de\/wp-json\/wp\/v2\/types\/atrakcje"}],"version-history":[{"count":1,"href":"https:\/\/energylandia.pl\/de\/wp-json\/wp\/v2\/atrakcje\/22750\/revisions"}],"predecessor-version":[{"id":311889,"href":"https:\/\/energylandia.pl\/de\/wp-json\/wp\/v2\/atrakcje\/22750\/revisions\/311889"}],"up":[{"embeddable":true,"href":"https:\/\/energylandia.pl\/de\/wp-json\/wp\/v2\/atrakcje\/22719"}],"wp:attachment":[{"href":"https:\/\/energylandia.pl\/de\/wp-json\/wp\/v2\/media?parent=22750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}