{"id":110893,"date":"2021-11-09T09:27:07","date_gmt":"2021-11-09T08:27:07","guid":{"rendered":"https:\/\/energylandia.pl\/?post_type=plm_atrakcje&#038;p=110893"},"modified":"2026-02-24T12:33:09","modified_gmt":"2026-02-24T11:33:09","slug":"crazy-barn","status":"publish","type":"atrakcje","link":"https:\/\/energylandia.pl\/de\/attraktionen\/sweet-valley\/crazy-barn\/","title":{"rendered":"Crazy Barn"},"content":{"rendered":"<p>Crazy Barn \u2013 eine Attraktion, die an eine l\u00e4ndliche Scheune erinnert und Euch richtig herumwirbelt! \ud83c\udf00<\/p>\n<p>Auf einer rotierenden Plattform montiert, dreht sich das Fahrzeug dank ver\u00e4nderlicher Neigung nicht nur um sich selbst, sondern \u00fcber die gesamte Plattform. Diese fantastische Attraktion ist voller \u00fcberraschender Effekte und aufregender Momente!<\/p>\n<p>Ihr einzigartiger Charakter entf\u00fchrt Euch in eine Welt neuer Erlebnisse, und das fr\u00f6hliche, verr\u00fcckte Scheunenthema verst\u00e4rkt den Spa\u00df \u2013 genau das, was wir alle lieben! \ud83c\udf89\ud83c\udf3e<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":107494,"parent":110807,"menu_order":1247,"template":"","class_list":["post-110893","atrakcje","type-atrakcje","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Crazy Barn - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crazy Barn - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\" \/>\n<meta property=\"og:description\" content=\"Crazy Barn \u2013 eine Attraktion, die an eine l\u00e4ndliche Scheune erinnert und Euch richtig herumwirbelt! \ud83c\udf00 Auf einer rotierenden Plattform montiert, dreht sich das Fahrzeug dank ver\u00e4nderlicher Neigung nicht nur um sich selbst, sondern \u00fcber die gesamte Plattform. Diese fantastische Attraktion ist voller \u00fcberraschender Effekte und aufregender Momente! Ihr einzigartiger Charakter entf\u00fchrt Euch in eine [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energylandia.pl\/de\/atrakcje\/sweet-valley\/crazy-barn\/\" \/>\n<meta property=\"og:site_name\" content=\"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EnergyLandia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-24T11:33:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/energylandia.pl\/wp-content\/uploads\/2021\/10\/crazy-barn.png\" \/>\n\t<meta property=\"og:image:width\" content=\"889\" \/>\n\t<meta property=\"og:image:height\" content=\"594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energylandia.pl\/de\/atrakcje\/sweet-valley\/crazy-barn\/\",\"url\":\"https:\/\/energylandia.pl\/de\/atrakcje\/sweet-valley\/crazy-barn\/\",\"name\":\"Crazy Barn - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\",\"isPartOf\":{\"@id\":\"https:\/\/energylandia.pl\/#website\"},\"datePublished\":\"2021-11-09T08:27:07+00:00\",\"dateModified\":\"2026-02-24T11:33:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/energylandia.pl\/de\/atrakcje\/sweet-valley\/crazy-barn\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energylandia.pl\/de\/atrakcje\/sweet-valley\/crazy-barn\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energylandia.pl\/de\/atrakcje\/sweet-valley\/crazy-barn\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/energylandia.pl\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atrakcje\",\"item\":\"https:\/\/energylandia.pl\/atrakcje\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sweet Valley\",\"item\":\"https:\/\/energylandia.pl\/de\/atrakcje\/sweet-valley\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Crazy Barn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energylandia.pl\/#website\",\"url\":\"https:\/\/energylandia.pl\/\",\"name\":\"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze\",\"description\":\"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!\",\"publisher\":{\"@id\":\"https:\/\/energylandia.pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energylandia.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/energylandia.pl\/#organization\",\"name\":\"Energylandia\",\"url\":\"https:\/\/energylandia.pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Energylandia\"},\"image\":{\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EnergyLandia\",\"https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA\",\"https:\/\/vm.tiktok.com\/Tw7YAK\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crazy Barn - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Crazy Barn - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","og_description":"Crazy Barn \u2013 eine Attraktion, die an eine l\u00e4ndliche Scheune erinnert und Euch richtig herumwirbelt! \ud83c\udf00 Auf einer rotierenden Plattform montiert, dreht sich das Fahrzeug dank ver\u00e4nderlicher Neigung nicht nur um sich selbst, sondern \u00fcber die gesamte Plattform. Diese fantastische Attraktion ist voller \u00fcberraschender Effekte und aufregender Momente! Ihr einzigartiger Charakter entf\u00fchrt Euch in eine [&hellip;]","og_url":"https:\/\/energylandia.pl\/de\/atrakcje\/sweet-valley\/crazy-barn\/","og_site_name":"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","article_publisher":"https:\/\/www.facebook.com\/EnergyLandia","article_modified_time":"2026-02-24T11:33:09+00:00","og_image":[{"width":889,"height":594,"url":"https:\/\/energylandia.pl\/wp-content\/uploads\/2021\/10\/crazy-barn.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/energylandia.pl\/de\/atrakcje\/sweet-valley\/crazy-barn\/","url":"https:\/\/energylandia.pl\/de\/atrakcje\/sweet-valley\/crazy-barn\/","name":"Crazy Barn - ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","isPartOf":{"@id":"https:\/\/energylandia.pl\/#website"},"datePublished":"2021-11-09T08:27:07+00:00","dateModified":"2026-02-24T11:33:09+00:00","breadcrumb":{"@id":"https:\/\/energylandia.pl\/de\/atrakcje\/sweet-valley\/crazy-barn\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energylandia.pl\/de\/atrakcje\/sweet-valley\/crazy-barn\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/energylandia.pl\/de\/atrakcje\/sweet-valley\/crazy-barn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/energylandia.pl\/de\/"},{"@type":"ListItem","position":2,"name":"Atrakcje","item":"https:\/\/energylandia.pl\/atrakcje\/"},{"@type":"ListItem","position":3,"name":"Sweet Valley","item":"https:\/\/energylandia.pl\/de\/atrakcje\/sweet-valley\/"},{"@type":"ListItem","position":4,"name":"Crazy Barn"}]},{"@type":"WebSite","@id":"https:\/\/energylandia.pl\/#website","url":"https:\/\/energylandia.pl\/","name":"ENERGYLANDIA - Rodzinny Park Rozrywki w Zatorze","description":"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!","publisher":{"@id":"https:\/\/energylandia.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energylandia.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/energylandia.pl\/#organization","name":"Energylandia","url":"https:\/\/energylandia.pl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Energylandia"},"image":{"@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EnergyLandia","https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA","https:\/\/vm.tiktok.com\/Tw7YAK\/"]}]}},"_links":{"self":[{"href":"https:\/\/energylandia.pl\/de\/wp-json\/wp\/v2\/atrakcje\/110893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energylandia.pl\/de\/wp-json\/wp\/v2\/atrakcje"}],"about":[{"href":"https:\/\/energylandia.pl\/de\/wp-json\/wp\/v2\/types\/atrakcje"}],"version-history":[{"count":3,"href":"https:\/\/energylandia.pl\/de\/wp-json\/wp\/v2\/atrakcje\/110893\/revisions"}],"predecessor-version":[{"id":312832,"href":"https:\/\/energylandia.pl\/de\/wp-json\/wp\/v2\/atrakcje\/110893\/revisions\/312832"}],"up":[{"embeddable":true,"href":"https:\/\/energylandia.pl\/de\/wp-json\/wp\/v2\/atrakcje\/110807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energylandia.pl\/de\/wp-json\/wp\/v2\/media\/107494"}],"wp:attachment":[{"href":"https:\/\/energylandia.pl\/de\/wp-json\/wp\/v2\/media?parent=110893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}