{"id":152784,"date":"2020-06-27T18:01:27","date_gmt":"2020-06-27T16:01:27","guid":{"rendered":"https:\/\/n.energylandia.pl\/noclegi\/osada-zator-family\/"},"modified":"2025-07-28T11:40:49","modified_gmt":"2025-07-28T09:40:49","slug":"osada-zator-family","status":"publish","type":"noclegi","link":"https:\/\/energylandia.pl\/cs\/ubytovani\/osada-zator-family\/","title":{"rendered":"Osada Zator Family"},"featured_media":0,"parent":0,"template":"","class_list":["post-152784","noclegi","type-noclegi","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Osada Zator Family - ubytov\u00e1n\u00ed v bl\u00edzkosti z\u00e1bavn\u00edho parku | Energylandia<\/title>\n<meta name=\"description\" content=\"Osada Zator Family - komfortn\u00ed ubytov\u00e1n\u00ed v bl\u00edzkosti Energylandie. Ide\u00e1ln\u00ed m\u00edsto pro odpo\u010dinek po n\u00e1ro\u010dn\u00e9m dni. Pod\u00edvejte se na nab\u00eddku a rezervujte si pobyt!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/energylandia.pl\/cs\/ubytovani\/osada-zator-family\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Osada Zator Family - ubytov\u00e1n\u00ed v bl\u00edzkosti z\u00e1bavn\u00edho parku | Energylandia\" \/>\n<meta property=\"og:description\" content=\"Osada Zator Family - komfortn\u00ed ubytov\u00e1n\u00ed v bl\u00edzkosti Energylandie. Ide\u00e1ln\u00ed m\u00edsto pro odpo\u010dinek po n\u00e1ro\u010dn\u00e9m dni. Pod\u00edvejte se na nab\u00eddku a rezervujte si pobyt!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energylandia.pl\/cs\/ubytovani\/osada-zator-family\/\" \/>\n<meta property=\"og:site_name\" content=\"Energylandia - park \u010d. 1 na sv\u011bt\u011b\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EnergyLandia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-28T09:40:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energylandia.pl\/cs\/ubytovani\/osada-zator-family\/\",\"url\":\"https:\/\/energylandia.pl\/cs\/ubytovani\/osada-zator-family\/\",\"name\":\"Osada Zator Family - ubytov\u00e1n\u00ed v bl\u00edzkosti z\u00e1bavn\u00edho parku | Energylandia\",\"isPartOf\":{\"@id\":\"https:\/\/energylandia.pl\/#website\"},\"datePublished\":\"2020-06-27T16:01:27+00:00\",\"dateModified\":\"2025-07-28T09:40:49+00:00\",\"description\":\"Osada Zator Family - komfortn\u00ed ubytov\u00e1n\u00ed v bl\u00edzkosti Energylandie. Ide\u00e1ln\u00ed m\u00edsto pro odpo\u010dinek po n\u00e1ro\u010dn\u00e9m dni. Pod\u00edvejte se na nab\u00eddku a rezervujte si pobyt!\",\"breadcrumb\":{\"@id\":\"https:\/\/energylandia.pl\/cs\/ubytovani\/osada-zator-family\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energylandia.pl\/cs\/ubytovani\/osada-zator-family\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energylandia.pl\/cs\/ubytovani\/osada-zator-family\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/energylandia.pl\/cs\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noclegi\",\"item\":\"https:\/\/energylandia.pl\/uk\/noclegi\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Osada Zator Family\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energylandia.pl\/#website\",\"url\":\"https:\/\/energylandia.pl\/\",\"name\":\"Energylandia - park \u010d. 1 na sv\u011bt\u011b\",\"description\":\"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!\",\"publisher\":{\"@id\":\"https:\/\/energylandia.pl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energylandia.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/energylandia.pl\/#organization\",\"name\":\"Energylandia\",\"url\":\"https:\/\/energylandia.pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Energylandia\"},\"image\":{\"@id\":\"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EnergyLandia\",\"https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA\",\"https:\/\/vm.tiktok.com\/Tw7YAK\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Osada Zator Family - ubytov\u00e1n\u00ed v bl\u00edzkosti z\u00e1bavn\u00edho parku | Energylandia","description":"Osada Zator Family - komfortn\u00ed ubytov\u00e1n\u00ed v bl\u00edzkosti Energylandie. Ide\u00e1ln\u00ed m\u00edsto pro odpo\u010dinek po n\u00e1ro\u010dn\u00e9m dni. Pod\u00edvejte se na nab\u00eddku a rezervujte si pobyt!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energylandia.pl\/cs\/ubytovani\/osada-zator-family\/","og_locale":"cs_CZ","og_type":"article","og_title":"Osada Zator Family - ubytov\u00e1n\u00ed v bl\u00edzkosti z\u00e1bavn\u00edho parku | Energylandia","og_description":"Osada Zator Family - komfortn\u00ed ubytov\u00e1n\u00ed v bl\u00edzkosti Energylandie. Ide\u00e1ln\u00ed m\u00edsto pro odpo\u010dinek po n\u00e1ro\u010dn\u00e9m dni. Pod\u00edvejte se na nab\u00eddku a rezervujte si pobyt!","og_url":"https:\/\/energylandia.pl\/cs\/ubytovani\/osada-zator-family\/","og_site_name":"Energylandia - park \u010d. 1 na sv\u011bt\u011b","article_publisher":"https:\/\/www.facebook.com\/EnergyLandia","article_modified_time":"2025-07-28T09:40:49+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/energylandia.pl\/cs\/ubytovani\/osada-zator-family\/","url":"https:\/\/energylandia.pl\/cs\/ubytovani\/osada-zator-family\/","name":"Osada Zator Family - ubytov\u00e1n\u00ed v bl\u00edzkosti z\u00e1bavn\u00edho parku | Energylandia","isPartOf":{"@id":"https:\/\/energylandia.pl\/#website"},"datePublished":"2020-06-27T16:01:27+00:00","dateModified":"2025-07-28T09:40:49+00:00","description":"Osada Zator Family - komfortn\u00ed ubytov\u00e1n\u00ed v bl\u00edzkosti Energylandie. Ide\u00e1ln\u00ed m\u00edsto pro odpo\u010dinek po n\u00e1ro\u010dn\u00e9m dni. Pod\u00edvejte se na nab\u00eddku a rezervujte si pobyt!","breadcrumb":{"@id":"https:\/\/energylandia.pl\/cs\/ubytovani\/osada-zator-family\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energylandia.pl\/cs\/ubytovani\/osada-zator-family\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/energylandia.pl\/cs\/ubytovani\/osada-zator-family\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/energylandia.pl\/cs\/"},{"@type":"ListItem","position":2,"name":"Noclegi","item":"https:\/\/energylandia.pl\/uk\/noclegi\/"},{"@type":"ListItem","position":3,"name":"Osada Zator Family"}]},{"@type":"WebSite","@id":"https:\/\/energylandia.pl\/#website","url":"https:\/\/energylandia.pl\/","name":"Energylandia - park \u010d. 1 na sv\u011bt\u011b","description":"ENERGYLANDIA - najwi\u0119kszy rodzinny Park Rozrywki w Polsce!","publisher":{"@id":"https:\/\/energylandia.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energylandia.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/energylandia.pl\/#organization","name":"Energylandia","url":"https:\/\/energylandia.pl\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Energylandia"},"image":{"@id":"https:\/\/energylandia.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EnergyLandia","https:\/\/www.youtube.com\/channel\/UCPj-Bs4Pfub_Bm04BOfyDoA","https:\/\/vm.tiktok.com\/Tw7YAK\/"]}]}},"_links":{"self":[{"href":"https:\/\/energylandia.pl\/cs\/wp-json\/wp\/v2\/noclegi\/152784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energylandia.pl\/cs\/wp-json\/wp\/v2\/noclegi"}],"about":[{"href":"https:\/\/energylandia.pl\/cs\/wp-json\/wp\/v2\/types\/noclegi"}],"wp:attachment":[{"href":"https:\/\/energylandia.pl\/cs\/wp-json\/wp\/v2\/media?parent=152784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}